{"id":5,"count":28,"description":"","link":"https:\/\/nonadecimal.com\/site\/category\/afterdeath\/","name":"Afterdeath","slug":"afterdeath","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Afterdeath Archives - Nonadecimal Creative<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nonadecimal.com\/site\/category\/afterdeath\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Afterdeath Archives - Nonadecimal Creative\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nonadecimal.com\/site\/category\/afterdeath\/\" \/>\n<meta property=\"og:site_name\" content=\"Nonadecimal Creative\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nonadecimal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/category\\\/afterdeath\\\/\",\"url\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/category\\\/afterdeath\\\/\",\"name\":\"Afterdeath Archives - Nonadecimal Creative\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/category\\\/afterdeath\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/category\\\/afterdeath\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Afterdeath\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/\",\"name\":\"Nonadecimal Creative\",\"description\":\"generating digital stories\",\"publisher\":{\"@id\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/#organization\",\"name\":\"Nonadecimal Creative\",\"url\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/nonadecimal.com\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/XIXavatar-5121.png?fit=512%2C512\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/nonadecimal.com\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/XIXavatar-5121.png?fit=512%2C512\",\"width\":512,\"height\":512,\"caption\":\"Nonadecimal Creative\"},\"image\":{\"@id\":\"https:\\\/\\\/nonadecimal.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Nonadecimal\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Nonadecimal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Afterdeath Archives - Nonadecimal Creative","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nonadecimal.com\/site\/category\/afterdeath\/","og_locale":"en_US","og_type":"article","og_title":"Afterdeath Archives - Nonadecimal Creative","og_url":"https:\/\/nonadecimal.com\/site\/category\/afterdeath\/","og_site_name":"Nonadecimal Creative","twitter_card":"summary_large_image","twitter_site":"@Nonadecimal","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/nonadecimal.com\/site\/category\/afterdeath\/","url":"https:\/\/nonadecimal.com\/site\/category\/afterdeath\/","name":"Afterdeath Archives - Nonadecimal Creative","isPartOf":{"@id":"https:\/\/nonadecimal.com\/site\/#website"},"breadcrumb":{"@id":"https:\/\/nonadecimal.com\/site\/category\/afterdeath\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/nonadecimal.com\/site\/category\/afterdeath\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nonadecimal.com\/site\/"},{"@type":"ListItem","position":2,"name":"Afterdeath"}]},{"@type":"WebSite","@id":"https:\/\/nonadecimal.com\/site\/#website","url":"https:\/\/nonadecimal.com\/site\/","name":"Nonadecimal Creative","description":"generating digital stories","publisher":{"@id":"https:\/\/nonadecimal.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nonadecimal.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nonadecimal.com\/site\/#organization","name":"Nonadecimal Creative","url":"https:\/\/nonadecimal.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nonadecimal.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/nonadecimal.com\/site\/wp-content\/uploads\/2015\/09\/XIXavatar-5121.png?fit=512%2C512","contentUrl":"https:\/\/i1.wp.com\/nonadecimal.com\/site\/wp-content\/uploads\/2015\/09\/XIXavatar-5121.png?fit=512%2C512","width":512,"height":512,"caption":"Nonadecimal Creative"},"image":{"@id":"https:\/\/nonadecimal.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Nonadecimal","https:\/\/www.youtube.com\/user\/Nonadecimal"]}]}},"_links":{"self":[{"href":"https:\/\/nonadecimal.com\/site\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nonadecimal.com\/site\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/nonadecimal.com\/site\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/nonadecimal.com\/site\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}